{"id":2433,"date":"2021-03-31T10:21:04","date_gmt":"2021-03-31T08:21:04","guid":{"rendered":"https:\/\/windowsreport.com\/ro\/?p=2433"},"modified":"2025-09-16T14:40:48","modified_gmt":"2025-09-16T11:40:48","slug":"aplicatia-mail-nu-functioneaza","status":"publish","type":"post","link":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/","title":{"rendered":"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10"},"content":{"rendered":"\n<p>Microsoft si-a imbunatatit mult aplicatia Mail incorporata in Windows 10. Dar chiar si in versiunea imbunatatita, unii oameni raporteaza ca nu pot primi e-mailuri sau chiar ca nu pot deschide aplicatia.<\/p>\n\n\n\n<p>Asadar, am pregatit cateva solutii care speram ca vor fi suficiente pentru rezolvarea problemei cu aplicatia Mail care nu functioneaza in Windows 10.<\/p>\n\n\n\n<p> Daca nu poti rula aplicatia Mail, poate fi un mare impediment, iar utilizatorii au raportat si urmatoarele probleme:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Aplicatia Windows 10 Mail nu se deschide<\/strong> &#8211; Multi utilizatori au raportat ca aplicatia Mail nu se deschide deloc din cauza acestei probleme. Daca aplicatia Mail nu se lanseaza, iti recomandam sa aplici unele dintre solutiile noastre.<\/li><li><strong>Aplicatia Windows 10 Mail nu se sincronizeaza<\/strong> &#8211; O alta problema similara care apare este incapacitatea de a sincroniza cutia postala. Aceasta problema va face ca aplicatia Mail sa fie aproape inutilizabila.<\/li><li><strong>Aplicatia Mail Windows 10 se blocheaza<\/strong> &#8211; Multi utilizatori au raportat, de asemenea, ca aplicatia lor de e-mail se blocheaza frecvent. Potrivit acestora, aplicatia se blocheaza de obicei la pornire, deci nu o pot folosi.<\/li><li><strong>Windows 10 Mail nu primeste e-mailuri<\/strong> &#8211; O alta problema des intalnita la aplicatia Mail este imposibilitatea de a primi e-mailuri. Aceasta poate fi o problema serioasa, dar ar trebui sa o poti rezolva cu solutiile noastre.<\/li><li><strong>Aplicatia Mail nu functioneaza in Windows 10, continua sa se inchida, sa se blocheze, sa se inchida<\/strong> &#8211; O alta problema similara pe care au raportat-o utilizatorii este blocarea frecventa a aplicatiei Mail. Potrivit utilizatorilor, aplicatia se opreste incontinuu, ceea ce ce inseamna ca nu pot citi sau trimite e-mailuri.<\/li><li><strong>Aplicatia Mail nu se actualizeaza<\/strong> &#8211; Multi utilizatori au raportat ca nu pot actualiza deloc aplicatia Mail. Daca nici nu poate fi accesata aplicatia Mail, rezolvarea acestei probleme ar putea fi dificila.<\/li><li><strong>Aplicatia Mail nu porneste in Windows 10<\/strong> &#8211; Problema este des intalnita si se manifesta prin imposibilitatea de a porni aplicatia Mail. Potrivit utilizatorilor, se pare ca aplicatia Mail se blocheaza imediat ce utilizatorii incearca sa o lanseze.<br><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Cum pot repara aplicatia Windows 10 Mail care nu primeste e-mailuri?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"> 1. Instaleaza un alt client de e-mail<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2019\/10\/email-client.jpg\"><img decoding=\"async\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2019\/10\/email-client.jpg\" alt=\"\" class=\"wp-image-512780\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Clientul de e-mail recomandat mai jos este destul de similar cu solutia nativa Windows din punctul de vedere al usurintei de utilizare.<\/p>\n\n\n\n<p> Acesta aduce capacitati mai puternice si mai complexe pentru a va imbunatati semnificativ experienta de e-mail.<\/p>\n\n\n\n<p>Acest client de e-mail prezinta o interfata foarte prietenoasa si intuitiva, care iti va permite sa gestionezi cu usurinta e-mailurile, atasamentele si contactele intr-o singura fereastra de Inbox unificata.<\/p>\n\n\n\n<p>Adaugand integrari cu alte solutii, te vei bucura de o multime de functionalitati pentru a acoperi toate nevoile tale de comunicare.<\/p>\n\n\n\n<p> Sa ne uitam rapid la <strong>caracteristicile sale cheie:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Gestionarea usoara a e-mailurilor si a contactelor dintr-o fereastra Inbox unificata<\/li><li>Optiuni de personalizare (numeroase teme gratuite de culoare, diferite stiluri de afisare adaptate pentru Windows si multe altele)<\/li><li>Integrari de aplicatii (Facebook, Twitter, Whatsapp, Dropbox, Google Calendar, Asana si multe altele)<\/li><li>Functia Snooze pentru a va separa si prioritiza e-mailurile<\/li><li>Notificari de sunete personalizate pentru e-mailurile primite si expediate<\/li><li>Comenzi rapide intuitive de la tastatura pentru arhivare, compunere, raspuns si redirectionare<\/li><li>Suport gratuit non-stop in mai multe limbi<\/li><\/ul>\n\n\n\n<section class=\"wp-block-windowsreport-companion-disposable-cta-block rmudcb\"><img decoding=\"async\" class=\"rmudcb__image\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/07\/Mailbird-Logo-210x160.png\" alt=\"Mailbird\" \/><div class=\"rmudcb__content\"><h3>Mailbird<\/h3><span>De ce sa te multumesti cu aplicatia Mail? Obtine mai multe optiuni cu un program mult mai usor de utilizat precum Mailbird!<\/span><\/div><div class=\"rmudcb__button\"><strong>Descarca<\/strong><a href=\"https:\/\/mailbird.evyy.net\/c\/393170\/362360\/4274?subId1=[current_url]\" class=\"btn btn--big btn--rounded btn--icon btn--basket\" target=\"_blank\">Viziteaza site-ul<\/a><\/div><\/section>\n\n\n\n<h3 class=\"wp-block-heading\"> 2. Verifica setarile de confidentialitate<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Acceseaza meniul <strong>Start<\/strong> si deschide aplicatia<strong> <\/strong><em>Settings<\/em>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"190\" class=\"aligncenter wp-image-130585 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-1.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><li>Da click pe sectiunea <strong>Privacy<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"188\" class=\"aligncenter wp-image-130587 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-2.png\" alt=\"Aplicatia Windows 10 Mail nu se sincronizeaza\"><\/a><\/li><li>Navigaheaza la <strong>Calendar<\/strong> in panoul din stanga.<\/li><li>Bifeaza <strong><strong>Let apps access my calendar<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"379\" class=\"aligncenter wp-image-130697 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-calendar-3.png\" alt=\"Aplicatia Windows 10 Mail se blocheaza\"><\/a><\/li><li> Apoi, in <em><em>Choose apps that can access calendar<\/em><\/em>, bifeaza <strong>Mail.<\/strong><\/li><\/ol>\n\n\n\n<p>Windows 10 este bine cunoscut ca un sistem de operare care colecteaza multe informatii si date de la utilizatori, inclusiv datele personale.<\/p>\n\n\n\n<p>Dar iti ofera, de asemenea, o mare varietate de setari de confidentialitate, asa ca poti interzice accesul Microsoft la aproape orice caracteristica a sistemului.<\/p>\n\n\n\n<p>Una dintre aceste caracteristici este, de asemenea, aplicatia Calendar, care este strans conectata la aplicatia de e-mail.<\/p>\n\n\n\n<p>Deci, daca ai blocat accesul Microsoft la aplicatia Calendar, aplicatia Mail nu va functiona la fel de bine.<\/p>\n\n\n\n<p>Dupa cum poti ghici, solutia la aceasta problema este foarte simpla, trebuie doar sa accesezi setarile si sa activezi accesul Microsoft la aplicatia Calendar.<\/p>\n\n\n\n<p>Reporneste computerul si incearca sa rulezi din nou aplicatia Mail, totul ar trebui sa functioneze bine. Dar daca nu, poti incerca si solutiile de mai jos. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">3. Schimba conexiunea securizata<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Deschide aplicatia <strong>Mail.<\/strong><\/li><li>Da clic pe pictograma<strong> Settings<\/strong> din coltul din stanga jos.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"130\" class=\"aligncenter wp-image-130645 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-1.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\"><\/a><\/li><li> Acceseaza <strong>Manage Accounts<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"243\" class=\"aligncenter wp-image-130647 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-2.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se inchide continuu\"><\/a><\/li><li> Da clic pe contul tau si acceseaza <strong><strong>Change mailbox settings<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"727\" height=\"361\" class=\"aligncenter wp-image-130649 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-3.png\" alt=\"Aplicatia de e-mail nu functioneaza in Windows 10 continua sa se blocheze\"><\/a><\/li><li> Asigura-te ca <strong>Server requires encrypted (SSL) connection<\/strong> si <strong>E-mail<\/strong>, in <em>optiunile de sincronizare<\/em> sunt bifate.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"459\" height=\"476\" class=\"aligncenter wp-image-130651 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-settings-4.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se opreste continuu\"><\/a><\/li><\/ol>\n\n\n\n<p>De asemenea, ai putea lua in considerare trecerea la un alt client de e-mail care sa nu-ti faca atatea probleme.<\/p>\n\n\n\n<p>Daca ai modificat setarile de confidentialitate si orice altceva este corect, dar tot nu poti primi mesaje in casuta de e-mail, incearca sa configurezi aplicatia Mail pentru a utiliza conexiunea securizata. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">4. Actualizeaza aplicatia Mail<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2019\/03\/Update-Banner.jpg\"><img decoding=\"async\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2019\/03\/Update-Banner.jpg\" alt=\"\" class=\"wp-image-540888\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa poti remedia problema pur si simplu actualizand-o.<\/p>\n\n\n\n<p>Multi utilizatori au raportat aceasta problema si, potrivit acestora, actualizarea aplicatiei la cea mai recenta versiune poate rezolva aceasta problema.<\/p>\n\n\n\n<p>Dupa actualizarea aplicatiei Mail la cea mai recenta versiune, problema ar trebui sa fie rezolvata si vei putea rula aplicatia Mail fara probleme.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">5. Instaleaza actualizarile Windows<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Apasati tasta <strong>Windows<\/strong> <strong>+ I<\/strong> pentru a deschide aplicatia Settings.<\/li><li> Navigheaza la sectiunea <strong><strong>Update &amp; security<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-update-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"185\" class=\"aligncenter wp-image-130671 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-update-1.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 continua sa blocheze\"><\/a><\/li><li> Acum da clic pe butonul <strong><strong>Check for updates<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-update-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"270\" class=\"aligncenter wp-image-130673 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-update-2.png\" alt=\"Aplicatia de e-mail nu se actualizeaza\"><\/a><\/li><\/ol>\n\n\n\n<p>Pentru a va mentine computerul sigur si stabil, este necesar sa instalezi actualizarile Windows. <\/p>\n\n\n\n<p>Potrivit utilizatorilor, au reusit sa rezolve aceasta problema pur si simplu instaland cele mai recente actualizari Windows.<\/p>\n\n\n\n<p>In mod implicit, Windows 10 instaleaza automat actualizarile in fundal, dar uneori se poate intampla sa omiti o actualizare importanta.<\/p>\n\n\n\n<p>Windows va verifica actualizarile disponibile si daca exista unele disponibile, Windows le va descarca in fundal si le va instala dupa ce repornesti computerul.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 6. Dezactiveaza setarile de sincronizare<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Deschideti <strong>aplicatia Settings<\/strong>.<\/li><li>Da click pe sectiunea <strong>Accounts.<\/strong><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-sync-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"601\" height=\"187\" class=\"aligncenter wp-image-130653 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-sync-1.png\" alt=\"Aplicatia Mail nu porneste Windows 10\"><\/a><\/li><li> Din meniul din stanga selecteaza <strong><strong>Sync your settings<\/strong><\/strong>.<\/li><li> In panoul din dreapta, localizeaza <strong>setarile de sincronizare<\/strong> si opreste-le culisand butonul spre Off.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-sync-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"500\" class=\"aligncenter wp-image-130655\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-sync-2.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><\/ol>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza pe PC-ul tau cu Windows 10, este posibil sa poti rezolva problema pur si simplu dezactivand setarile de sincronizare.<\/p>\n\n\n\n<p>Dupa dezactivarea setarilor de sincronizare, trebuie doar sa repornesti computerul pentru a aplica modificarile.<\/p>\n\n\n\n<p>Odata ce computerul reporneste, problema ar trebui sa fie rezolvata. Daca totul functioneaza bine, poti activa din nou setarile de sincronizare. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 7. Schimba setarile de localizare<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Apasa <strong>tasta Windows + S<\/strong> si tasteaza <em>control panel<\/em>.<\/li><li> Acum selectateaza <strong>Control Panel<\/strong> din lista de rezultate.<img decoding=\"async\" class=\"wp-image-638585\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/Control-Panel-start.jpg\" alt=\"\"><\/li><li> Selectateaza<strong> Region<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"103\" class=\"aligncenter wp-image-130605 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-2.png\" alt=\"Aplicatia Windows 10 Mail se blocheaza\"><\/a><\/li><li> Navigati la tab-ul<strong> Location<\/strong> si seteaza <em><em>Home location<\/em>\u00a0to your country<\/em> pentru tara ta.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"500\" class=\"aligncenter wp-image-130607\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-3.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\"><\/a><\/li><li> Acum acceseaza tab-ul<strong> Administrative<\/strong> si da click pe butonul <em><em>Change system locale<\/em><\/em>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"500\" class=\"aligncenter wp-image-130609\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-4.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se inchide continuu\"><\/a><\/li><li> Selecteaza tara ta din meniul <strong>Current system locale<\/strong> si da click pe <em>OK<\/em> pentru a salva modificarile.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-5.png\"><img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"220\" class=\"aligncenter wp-image-130611 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-5.png\" alt=\"Aplicatia de e-mail nu functioneaza in Windows 10 continua sa se blocheze\"><\/a><\/li><li> Acum da click pe <strong>Apply<\/strong> si <strong>OK<\/strong> in<strong> <\/strong>fereastra Region. <br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-6.png\"><img loading=\"lazy\" decoding=\"async\" width=\"445\" height=\"500\" class=\"aligncenter wp-image-130613\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-localization-6.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se opreste continuu\"><\/a><\/li><\/ol>\n\n\n\n<p>Potrivit utilizatorilor, este posibil sa poti rezolva problema cu aplicatia Mail pur si simplu modificand setarile de localizare.<\/p>\n\n\n\n<p>Utilizatorii au raportat ca aplicatia Mail nu functioneaza in Windows 10, dar dupa modificarea setarilor de localizare, problema a fost rezolvata in totalitate.<\/p>\n\n\n\n<p>Dupa modificarea setarilor locale ale sistemului, verifica daca problema cu aplicatia Mail apare in continuare. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 7. Foloseste Command Prompt, PowerShell si DISM<\/h3>\n\n\n\n<p> <strong>7.1 Ruleaza o scanare System File Checker<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Apasa tastele <strong>Windows + S<\/strong> pentru a deschide functia de cautare si tasteaza <em>cmd<\/em>.<\/li><li>Selectati <strong>Run as administrator<\/strong> din lista pentru a deschide <em>Command Prompt<\/em> ca administrator.<ul><li> In cazul in care Command Prompt nu este disponibil, nu ezita sa folosesti in schimb <strong>PowerShell<\/strong>.<\/li><\/ul><\/li><li> Cand se deschide fereastra, tasteaza aceasta comanda si apasa <strong>Enter<\/strong> pentru a o executa:<ul><li> <code><strong>sfc \/scannow<\/strong><\/code><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"547\" height=\"172\" class=\"aligncenter wp-image-130591 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-2.png\" alt=\"Aplicatia de e-mail nu se actualizeaza\"><\/a><\/li><\/ul><\/li><li> Procesul de scanare va incepe imediat. Scanarea SFC poate dura 10-15 minute, deci ai rabdare si nu o intrerupe.<\/li><\/ol>\n\n\n\n<p>Dupa finalizarea scanarii SFC, verifica daca problema persista. Daca scanarea SFC nu poate remedia problema sau daca nu poti rula deloc scanarea SFC, iti recomandam sa incerci scanarea DISM.<\/p>\n\n\n\n<p> <strong>7.2 Ruleaza o scanare DISM<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li> Porneste <strong>Command Prompt<\/strong> ca administrator, ca in solutia precedenta.<\/li><li> Introdu aceasta linie de la tastatura si apasa <strong>Enter<\/strong> pentru a o rula:<ul><li> <code><strong>dism \/online \/cleanup-image \/restorehealth<\/strong><\/code><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"593\" height=\"221\" class=\"aligncenter wp-image-130593 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-3.png\" alt=\"Aplicatia Mail nu porneste Windows 10\"><\/a><\/li><\/ul><\/li><li> Scanarea DISM va incepe imediat. Aceasta scanare poate dura 15-20 de minute, deci nu o intrerupe.<\/li><\/ol>\n\n\n\n<p>Potrivit utilizatorilor, daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa poti remedia problema efectuand scanari SFC si DISM.<\/p>\n\n\n\n<p>Aceste scanari sunt concepute pentru a repara fisierele de sistem corupte si, dupa ce le efectuati, problema ar trebui rezolvata.<\/p>\n\n\n\n<p>Dupa finalizarea scanarii DISM, verificati daca problema persista. <\/p>\n\n\n\n<p>Daca nu ai putut rula o scanare SFC inainte, o poti face dupa efectuarea unei scanari DISM. Acum verifica daca problema cu aplicatia Mail apare in continuare.<\/p>\n\n\n\n<p>Unii utilizatori recomanda, de asemenea, folosirea unei comanzi PowerShell pentru a remedia aceasta problema. <\/p>\n\n\n\n<p>Trebuie sa te avertizam ca aceasta comanda este destul de puternica si poate provoca probleme cu alte aplicatii daca nu o folosesti corect.<\/p>\n\n\n\n<p>Deoarece aceasta comanda este potential periculoasa, este alegerea ta daca iti asumi acest risc.<\/p>\n\n\n\n<p> <strong>7.2 Ruleaza o comanda PowerShell<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li> Da click dreapta pe butonul Start si selecteaza <strong>Windows PowerShell (Admin)<\/strong> din lista.<ul><li>Aceasta comanda necesita privilegii administrative si, daca nu pornesti PowerShell ca administrator, nu o vei putea executa.<\/li><\/ul><\/li><li> Cand se deschide PowerShell, scrie urmatoarea comanda si apasa <strong>Enter<\/strong> pentru a o rula:<ul><li> <code><strong>Get-AppXPackage -AllUsers |Where-Object {$_.InstallLocation -like \"*SystemApps*\"} | Foreach {Add-AppxPackage -DisableDevelopmentMode -Register \"$($_.InstallLocation)AppXManifest.xml\"}<\/strong><\/code><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"841\" height=\"173\" class=\"aligncenter wp-image-130595 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-cmd-4.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><\/ul><\/li><\/ol>\n\n\n\n<p> Dupa executarea comenzii PowerShell, problemele cu aplicatia Mail ar trebui sa dispara. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">8. Reinstaleaza aplicatia Mail<\/h3>\n\n\n\n<p><strong>8.1 Dezinstaleaza aplicatia Mail folosind PowerShell<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Asigura-te ca esti conectat ca administrator.<\/li><li>Acum porneste <strong>PowerShell<\/strong> ca administrator la fel ca in solutia precedenta.<\/li><li>Tasteaza aceasta linie de comanda si apasa <strong>Enter<\/strong> pentru a o rula:<ul><li> <code><strong>get-appxpackage *microsoft.windowscommunicationsapps* | remove-appxpackage<\/strong><\/code><br><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"163\" class=\"aligncenter wp-image-130665 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-1.png\" alt=\"Aplicatia Windows 10 Mail nu se sincronizeaza\"><\/a><\/li><\/ul><\/li><\/ol>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa poti remedia problema pur si simplu reinstaland-o. <\/p>\n\n\n\n<p>Pentru a reinstala aplicatia Mail, trebuie sa folosesti PowerShell executand comanda de sus.<\/p>\n\n\n\n<p><strong>8.2 Dezinstaleaza aplicatia Mail utilizand un program de dezinstalare dedicat<\/strong><\/p>\n\n\n\n<p>Daca ti se pare prea complicat sa folosesti PowerShell, poti dezinstala aplicatia Mail folosind un software de dezinstalare dedicat pentru PC.<\/p>\n\n\n\n<p>Instrumentul recomandat mai jos iti permite sa elimini orice aplicatii de pe computer, chiar si cele mai incapatanate si se va asigura ca nu va lasa resturi in urma.<\/p>\n\n\n\n<p>Dupa ce rulezi aceasta aplicatie, veti recupera spatiul liber de pe computerul care a fost ocupat cu ramasitele tuturor fisierelor inutile despre care nici nu stiai ca exista pe hard disk.<\/p>\n\n\n\n<p> <strong>\u21d2<\/strong> <strong><a href=\"https:\/\/store.iobit.com\/affiliate.php?ACCOUNT=LOBIT&amp;AFFILIATE=84641&amp;PATH=https%3A%2F%2Fwww.iobit.com%2Fen%2Fadvanceduninstaller.php%3FAFFILIATE%3D84641&amp;AFFSRC=[current_url]\" target=\"_blank\" rel=\"noreferrer noopener\">Descarca IObit Uninstaller<\/a><\/strong><\/p>\n\n\n\n<p><strong>8.3 Reinstaleaza aplicatia Mail<\/strong> <strong>din Microsoft Store<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li> Apasati tastele<strong> Windows + S<\/strong> si tasteaza <em>microsoft store<\/em>.<\/li><li> Selectati <strong>Microsoft Store<\/strong> din lista de rezultate. <img decoding=\"async\" class=\"wp-image-638593\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/microsoft-store-open.jpg\" alt=\"\"><\/li><li> In bara de cautare, scrie <em>Mail<\/em><strong> <\/strong>si selecteaza <strong>Mail and Calendar<\/strong> din lista de rezultate.<br><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"530\" height=\"266\" class=\"aligncenter wp-image-130669 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-3.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\"><\/a><\/li><li> Acum da click pe butonul<strong> Install<\/strong> pentru a instala din nou aplicatia Mail.<\/li><\/ol>\n\n\n\n<p>Urmeaza pasii de mai sus pentru a instala din nou aplicatia Mail din Microsoft Store.<\/p>\n\n\n\n<p><strong>8.4 Reinstaleaza aplicatia Mail utilizand PowerShell<\/strong><\/p>\n\n\n\n<p>Mai multi utilizatori sustin ca puteti reinstala aplicatia Mail pur si simplu pornind PowerShell ca administrator si executand aceasta comanda: <code><strong>Get-AppxPackage -AllUsers| Foreach {Add-AppxPackage -DisableDevelopmentMode -Register \u201c$($_.InstallLocation)AppXManifest.xml\u201d}<\/strong><\/code><br><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"163\" class=\"aligncenter wp-image-130665 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-uninstall-1.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se inchide continuu\"><\/a><\/p>\n\n\n\n<p>Dupa reinstalarea aplicatiei Mail, problema ar trebui rezolvata complet.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">9. Schimbati proprietarul directorului windows \/ communications \/ apps<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Navigheaza la acest director:<ul><li> <code><strong>C:\\Program Files<\/strong><\/code><\/li><\/ul><\/li><li>Cauta directorul WindowsApps.<\/li><li>Daca acest director nu este disponibil, trebuie sa accesezi meniu <strong>View<\/strong> si sa bifezi <em>Hidden items<\/em> ca in imaginea de mai jos.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-view-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"145\" class=\"aligncenter wp-image-130675 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-view-1.png\" alt=\"Aplicatia de e-mail nu functioneaza in Windows 10 continua sa se blocheze\"><\/a><br> Acum gaseste directorul<strong> WindowsApps<\/strong>, da click dreapta pe el si alege <strong>Properties<\/strong> din meniu.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"349\" height=\"194\" class=\"aligncenter wp-image-130615 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-1.png\" alt=\"Aplicatia Mail nu functioneaza in inchiderea Windows 10\"><\/a><\/li><li>Acceseaza tab-ul <strong>Security<\/strong> si da click pe <em>Advanced<\/em>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"363\" height=\"481\" class=\"aligncenter wp-image-130617 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-2.png\" alt=\"Aplicatia de e-mail nu se actualizeaza\"><\/a><\/li><li>Acum da click pe <strong>Change<\/strong> langa sectiunea <em>Owner.<\/em><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"455\" height=\"216\" class=\"aligncenter wp-image-130619 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-3.png\" alt=\"Aplicatia Mail nu porneste Windows 10\"><\/a><\/li><li>Introdu numele contului tau de utilizator in campul <strong><strong>Enter the object name to select<\/strong><\/strong>.<\/li><li>Da click pe butonul <strong><strong>Check Names<\/strong><\/strong>.<\/li><li>Daca totul este in ordine, da click pe <strong>OK<\/strong> pentru a salva modificarile.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"457\" height=\"251\" class=\"aligncenter wp-image-130621 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-4.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><li>Da click pe <strong>Apply<\/strong> si <em>OK<\/em> pentru a salva modificarile.<\/li><li>Navigheaza acum la directorul <strong>WindowsApps.<\/strong><\/li><li>Gaseste directorul <strong>microsoft.windowscommunicationsapps<\/strong>, da click dreapta pe el si alege <em>Properties<\/em><strong> <\/strong>din meniu.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-5.png\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"271\" class=\"aligncenter wp-image-130623 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-5.png\" alt=\"Aplicatia Windows 10 Mail nu se sincronizeaza\"><\/a><\/li><li>Acum schimbati proprietarul directorului repetand <em>pasii 3-5<\/em>.<\/li><li>Asigura-te ca bifezi <strong><strong>Replace owner on sub containers and objects<\/strong><\/strong> si da click pe <em>Apply<\/em><strong> <\/strong>si <strong>OK<\/strong> pentru a salva modificarile.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-7.png\"><img loading=\"lazy\" decoding=\"async\" width=\"758\" height=\"484\" class=\"aligncenter wp-image-130627 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-7.png\" alt=\"Aplicatia Windows 10 Mail se blocheaza\"><\/a> .<\/li><li>Deschide din nou optiunea <strong>Advanced<\/strong>.<\/li><li>Da click pe butonul <strong><strong>Change permissions<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-8.png\"><img loading=\"lazy\" decoding=\"async\" width=\"332\" height=\"165\" class=\"aligncenter wp-image-130629 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-8.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\"><\/a><\/li><li>Acum gaseste <strong>Users<\/strong> in lista si da dublu click pe acesta.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-9.png\"><img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"263\" class=\"aligncenter wp-image-130631 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-9.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se inchide continuu\"><\/a><\/li><li>Bifeaza <strong>Full control<\/strong> si da click pe <em>OK<\/em>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-10.png\"><img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"511\" class=\"aligncenter wp-image-130633 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-owner-10.png\" alt=\"Aplicatia de e-mail nu functioneaza in Windows 10 continua sa se blocheze\"><\/a><\/li><li>Da clic pe <strong>Apply<\/strong> si <em>OK<\/em><strong> <\/strong>pentru a salva modificarile.<\/li><li>Acum trebuie doar sa repeti <em>pasii 7-13<\/em> pentru toate celelalte directoare <strong>microsoft.windowscommunicationsapps.<\/strong><ul><li>Noi aveam doar doua directoare<em> microsoft.windowscommunicationsapps<\/em> pe computerul nostru, dar s-ar putea ca tu sa ai mai multe.<\/li><li>Pentru a remedia aceasta problema, este important sa schimbi proprietarul acestor directoare si sa obtii controlul deplin asupra lor.<\/li><\/ul><\/li><\/ol>\n\n\n\n<p>Daca aplicatia  Mail nu functioneaza in Windows 10, poti rezolva problema schimband proprietarul directorului <em>WindowsApps.<\/em><\/p>\n\n\n\n<p>Acest director contine toate fisierele necesare pe care le foloseste aplicatia Mail si, dupa schimbarea dreptului de proprietate asupra acestuia, problemele cu aplicatia Mail ar trebui sa dispara.<\/p>\n\n\n\n<p>Aceasta este o solutie avansata, deci daca decizi sa o utilizezi, fii foarte precaut si urmeaza pasii indeaproape.<\/p>\n\n\n\n<p>Potrivit unor utilizatori, pur si simplu prin schimbarea proprietarului <em>directorului WindowsApps<\/em>, problema ar trebui rezolvata. <\/p>\n\n\n\n<p>Daca acest lucru nu ajuta, este posibil sa trebuiasca sa efectuezi toti pasii din aceasta solutie.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">10. Dezactiveaza conexiunea la Internet<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/04\/No-Internet-1.jpg\"><img decoding=\"async\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/04\/No-Internet-1.jpg\" alt=\"\" class=\"wp-image-529240\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa poti rezolva problema cu aceasta solutie.<\/p>\n\n\n\n<p>Potrivit utilizatorilor, puteti remedia aceasta problema pur si simplu dezactivand conexiunea la internet pentru cateva minute, reactiveaz-o si incearca din nou sa rulezi aplicatia Mail.<\/p>\n\n\n\n<p>Putini utilizatori au raportat ca aceasta solutie a functionat pentru ei, deci nu strica sa o incerci. Aceasta pare a fi o solutie simpla si ar putea fi necesar sa o repeti daca problema reapare.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 11. Impiedica aplicatia Mail and Calendar sa iti acceseze locatia<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Deschideti <strong>aplicatia Settings<\/strong>.<\/li><li> Navigheaza la sectiunea <strong>Privacy<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-privacy-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"613\" height=\"198\" class=\"aligncenter wp-image-130635 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-privacy-1.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se opreste continuu\"><\/a><\/li><li>Alegeti <strong>Location<\/strong> din meniul din stanga.<\/li><li>Acum deruleaza in jos si dezactiveaza serviciul de localizare pentru aplicatia <strong>Mail and Calendar.<\/strong><\/li><li>Alternativ, poti dezactiva complet serviciul de localizare pe computerul tau.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-privacy-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"805\" height=\"367\" class=\"aligncenter wp-image-130637 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-privacy-2.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 continua sa blocheze\"><\/a><\/li><\/ol>\n\n\n\n<p>Multi utilizatori au raportat ca aplicatia Mail nu functioneaza pe computerul lor. Potrivit acestora, problema a fost cauzata de un serviciu de localizare.<\/p>\n\n\n\n<p>Pentru a remedia problema, trebuie sa impiedici ca aplicatia Mail and Calendar sa iti acceseze locatia.<\/p>\n\n\n\n<p>Dupa dezactivarea serviciului de localizare pentru aplicatia Mail, problema ar trebui rezolvata complet. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">12. Actualizeaza driverele placii grafice<\/h3>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2018\/03\/GPU-2.jpg\"><img decoding=\"async\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2018\/03\/GPU-2.jpg\" alt=\"\" class=\"wp-image-537856\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Mai multi utilizatori au raportat ca aplicatia Mail se blocheaza constant pe computerul lor. Pentru a remedia problema, utilizatorii sugereaza actualizarea driverul placii grafice.<\/p>\n\n\n\n<p> Potrivit utilizatorilor, a existat o <a href=\"https:\/\/windowsreport.com\/no-sound-nvidia-graphics-drivers-update\/\" target=\"_blank\" rel=\"noopener noreferrer\">problema cu grafica Nvidia<\/a> , dar dupa actualizarea driverului la cea mai recenta versiune, problema a fost rezolvata.<\/p>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, viziteaza site-ul web Nvidia si instalezi cele mai recente drivere pentru placa grafica. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">13. Efectuati o restaurare a sistemului<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Apasa tastele <strong>Windows + S<\/strong> si tasteaza <em>system restore<\/em>.<\/li><li>Alege <strong>Create a restore point<\/strong> din meniu.<\/li><li>Fereastra <em>System Properties<\/em> va aparea imediat.<\/li><li>Da click pe butonul <strong><strong>System Restore<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"412\" height=\"468\" class=\"aligncenter wp-image-130659 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-2.png\" alt=\"Aplicatia Mail nu porneste Windows 10\"><\/a><\/li><li> Cand <em>se deschide fereastra<\/em>, da click pe <strong>Next<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"566\" height=\"459\" class=\"aligncenter wp-image-130661 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-3.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><li> Acum vei vedea o lista cu toate punctele de restaurare disponibile. Daca este disponibila, bifeaza optiunea <strong><strong>Show more restore points<\/strong><\/strong>.<\/li><li> Acum selecteaza punctul de restaurare dorit si da click pe <strong>Next<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"566\" height=\"459\" class=\"aligncenter wp-image-130663 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-system-restore-4.png\" alt=\"Aplicatia Windows 10 Mail nu se sincronizeaza\"><\/a><\/li><li> Urmeaza instructiunile de pe ecran pentru a finaliza procesul de restaurare.<\/li><\/ol>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa poti rezolva aceasta problema utilizand functia System Restore.<\/p>\n\n\n\n<p>Dupa restaurarea computerului, verifica daca problema este rezolvata. Mai multi utilizatori au raportat ca System Restore a rezolvat problema pentru ei, deci nu ezita sa o incerci urmand pasii de mai sus. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 14. Creeaza un cont de utilizator nou<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Deschideti aplicatia<strong> Settings<\/strong> si navigheaza la sectiunea <strong>Accounts.<\/strong><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"170\" class=\"aligncenter wp-image-130679 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-1.png\" alt=\"Aplicatia Windows 10 Mail se blocheaza\"><\/a><\/li><li> Navigheaza la <strong><strong>Family &amp; other people<\/strong>\u00a0<\/strong>din panoul din stanga.<\/li><li> Acum da click pe <strong><strong>Add someone else to this PC<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-2.png\"><img decoding=\"async\" class=\"aligncenter wp-image-130681 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-2.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\" style=\"width: 600px\"><\/a><\/li><li> Selecteaza<strong>\u00a0<strong>I don\u2019t have this person\u2019s sign-in information<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"168\" class=\"aligncenter wp-image-130683 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-3.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se inchide continuu\"><\/a><\/li><li> Acum da click pe <strong><strong>Add a user without a Microsoft account<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-4.png\"><img loading=\"lazy\" decoding=\"async\" width=\"652\" height=\"149\" class=\"aligncenter wp-image-130581 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-4.png\" alt=\"Aplicatia de e-mail nu functioneaza in Windows 10 continua sa se blocheze\"><\/a><\/li><li> Introdu numele de utilizator dorit si da click pe <strong>Next<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-5.png\"><img decoding=\"async\" class=\"aligncenter wp-image-130583 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-account-5.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 se opreste continuu\" style=\"width: 500px\"><\/a><\/li><\/ol>\n\n\n\n<p>Se pare ca aplicatia Mail nu functioneaza in Windows 10 daca contul dvs. de utilizator este deteriorat. Cu toate acestea, poti rezolva aceasta problema creand un cont de utilizator nou.<\/p>\n\n\n\n<p>Dupa crearea unui cont nou, trebuie sa te loghezi in acest cont si sa verifici daca aplicatia Mail functioneaza. Daca da, va trebui sa muti fisierele personale si sa utilizezi noul cont ca pe unul principal.<\/p>\n\n\n\n<p>Putini utilizatori au raportat ca au remediat problema prin crearea unui nou cont de utilizator Microsoft. Pentru a face acest lucru, mai intai, trebuie sa va schimbati contul de la Microsoft la local.<\/p>\n\n\n\n<p>Acest lucru este relativ simplu si il poti face urmand acesti pasi:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li> Deschideti aplicatia<strong> <\/strong><em>Settings<\/em> si acceseaza sectiunea <strong>Accounts.<\/strong><\/li><li> In sectiunea<em> Your info,<\/em> da click pe <strong><strong>Sign in with a local account instead<\/strong><\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"500\" class=\"aligncenter wp-image-130597\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-1.png\" alt=\"Aplicatia Mail nu functioneaza in Windows 10 continua sa blocheze\"><\/a><\/li><li> Introdu parola contului tau si da click pe <strong>Next<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"500\" class=\"aligncenter wp-image-130599\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-2.png\" alt=\"Aplicatia de e-mail nu se actualizeaza\"><\/a><\/li><li> Acum introdu numele de utilizator dorit si da click pe <strong>Next<\/strong>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"500\" class=\"aligncenter wp-image-130601\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-local-account-3.png\" alt=\"Aplicatia Mail nu porneste Windows 10\"><\/a><\/li><li> In cele din urma, da click pe butonul <strong><strong>Sign out and finish<\/strong><\/strong>.<\/li><\/ol>\n\n\n\n<p>Acum trebuie doar sa te conectezi din nou la contul tau local si sa adaugi un cont nou urmand <em>pasii 1-2<\/em> de la inceputul acestei solutii.<\/p>\n\n\n\n<p>Asigura-te ca introduci adresa de e-mail a contului tau Microsoft si urmeaza instructiunile de pe ecran pentru a crea un cont nou.<\/p>\n\n\n\n<p> Dupa ce faci acest lucru, comuta la un cont nou si verifica daca problema este rezolvata. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 15. Reseteaza aplicatia Mail<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Deschide aplicatia<strong> Settings<\/strong> si navigheaza la sectiunea <em>Apps.<\/em><br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"151\" class=\"aligncenter wp-image-130639 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-1.png\" alt=\"Aplicatia Windows 10 Mail nu se deschide\"><\/a><\/li><li>Va aparea o lista cu toate aplicatiile instalate.<\/li><li>Selecteaza <strong>Mail and Calendar<\/strong> si da click pe <em><em>Advanced options<\/em><\/em>.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"797\" height=\"160\" class=\"aligncenter wp-image-130641 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-2.png\" alt=\"Aplicatia Windows 10 Mail nu se sincronizeaza\"><\/a><\/li><li>Acum da click pe butonul <strong>Reset.<\/strong> Va aparea o fereastra de confirmare.<\/li><li>Da clic pe <strong>butonul Reset<\/strong> pentru a continua.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"454\" height=\"371\" class=\"aligncenter wp-image-130643 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-reset-3.png\" alt=\"Aplicatia Windows 10 Mail se blocheaza\"><\/a><\/li><\/ol>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, este posibil sa o poti remedia pur si simplu resetand-o. Aceasta este o procedura destul de simpla si o poti face urmand pasii de mai sus.<\/p>\n\n\n\n<p>Dupa resetarea aplicatiei Mail, datele acesteia vor fi sterse si cele mai multe probleme cu aceasta vor fi rezolvate. <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">16. Foloseste troubleshooter-ul Windows Store Apps<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li> Apasa tastele <strong>Windows + S<\/strong>, tasteaza <em>troubleshooter<\/em> si selecteaza Troubleshoot settings din rezultate. <img decoding=\"async\" class=\"wp-image-638619\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/troubleshoot-settings.png\" alt=\"\"><\/li><li>Da clic pe <strong><strong>Additional troubleshooters<\/strong><\/strong>. <img decoding=\"async\" class=\"wp-image-638620\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/Additional-troubleshooters.jpg\" alt=\"\"><\/li><li>Acum selecteaza instrumentul de depanare Windows Store Apps si da click pe butonul <strong><strong>Run the troubleshooter<\/strong><\/strong>. <img decoding=\"async\" class=\"wp-image-638622\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/WIndows-Store-Apps-troubleshooter.png\" alt=\"\"><\/li><li> Daca sistemul va detecta probleme cu aplicatia Mail, o va repara.<\/li><li> In cele din urma, vei primi si sugestia de a reseta o aplicatie.<img decoding=\"async\" class=\"wp-image-638623\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/Reset-the-app.png\" alt=\"\"><\/li><li> Da click pe butonul <strong><strong>Open Apps &amp; features<\/strong><\/strong>.<\/li><li>Selecteaza aplicatia Mail and Calendar din lista si selecteaza Advanced options. <img decoding=\"async\" class=\"wp-image-638627\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/Mail-and-calendar-advanced-options.jpg\" alt=\"\"><\/li><li>Deruleaza in jos pana cand vezi optiunea<strong> Reset<\/strong> si da click pe ea. <img decoding=\"async\" class=\"wp-image-638628\" style=\"width: 500px\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/09\/Reset-mail-and-calendar.png\" alt=\"\"><\/li><li>Vei primi un mesaj de avertizare ca aceasta actiune va sterge toate datele aplicatiei, inclusiv preferintele si datele de conectare. Da click pe butonul Reset daca esti de acord cu acest lucru.<\/li><\/ol>\n\n\n\n<p>Daca ai probleme cu aplicatia Mail si alte aplicatii Microsoft Store, este posibil sa o poti remedia utilizand aceasta solutie.<\/p>\n\n\n\n<p>Troubleshooter-ul va verifica aplicatiile universale si va remedia eventualele probleme. Dupa ce folosesti aceasta solutie, verifica daca aplicatia de e-mail functioneaza.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\"> 17. Reseteaza memoria cache a Microsoft Store<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Porneste <strong>Command Prompt<\/strong> ca administrator.<\/li><li> Cand se deschide fereastra, tasteaza comanda<strong> <\/strong><em>wsreset.exe<\/em> si apasa <strong>Enter<\/strong> pentru a o executa.<br> <a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-wsreset-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"483\" height=\"177\" class=\"aligncenter wp-image-130677 size-full\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2017\/09\/mail-app-not-working-wsreset-1.png\" alt=\"Windows 10 Mail nu primeste e-mailuri\"><\/a><\/li><li>Asteapta cateva momente in timp ce Windows sterge memoria cache.<\/li><\/ol>\n\n\n\n<p>Potrivit utilizatorilor, s-ar putea sa rezolvi aceasta problema pur si simplu prin resetarea memoriei cache Microsoft Store. <\/p>\n\n\n\n<p>Aceasta nu este o solutie universala, dar putini utilizatori au raportat ca a functionat pentru ei, asa ca nu strica sa o incerci.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"wp-block-heading\">18. Efectueaza o actualizare la Windows<\/h3>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/07\/System-Update-upgrade.jpg\"><img decoding=\"async\" src=\"https:\/\/windowsreport.com\/wp-content\/uploads\/2020\/07\/System-Update-upgrade.jpg\" alt=\"\" class=\"wp-image-542145\" \/><\/a><\/figure>\n\n\n\n<ol class=\"wp-block-list\"><li>Descarca <a href=\"https:\/\/windowsreport.com\/windows-10-creators-update-iso-files-download\/\" target=\"_blank\" rel=\"noopener noreferrer\">fisierul ISO Windows 10<\/a> de pe site-ul web Microsoft. Da dublu clic pe fisierul ISO pentru al monta.<\/li><li>Navigheaza acum la <strong>My computer<\/strong> si deschide fisierul ISO montat.<\/li><li>Gaseste <strong>setup.exe<\/strong> si da dublu click pe acesta pentru a-l rula.<\/li><li>Acum ti se va cere sa descarci si sa instalati actualizarile. Acest lucru nu este obligatoriu, deci poti selecta optiunea <strong><strong>Not right now<\/strong><\/strong>. Da clic pe <strong>Next<\/strong> pentru a continua.<\/li><li>Urmeaza instructiunile de pe ecran pana cand ajungi la ecranul <em>Ready to install<\/em>. Da clic pe optiunea <strong><strong>Change what to keep<\/strong>.<\/strong><\/li><li>Selecteaza optiunea <strong>Keep personal files and apps<\/strong> si da click pe <strong>Next<\/strong>.<\/li><li>Acum va incepe procesul de actualizare. Acest lucru poate dura ceva timp, deci nu il intrerupe.<\/li><\/ol>\n\n\n\n<p>Daca aplicatia Mail nu functioneaza in Windows 10, poate fi necesar sa efectuezi o actualizare Windows pentru a o remedia. Acest proces iti va actualiza Windows 10, pastrand in acelasi timp toate fisierele intacte.<\/p>\n\n\n\n<p>Dupa finalizarea procesului, Windows 10 va fi actualizat la cea mai recenta versiune, iar problemele cu aplicatia Mail vor fi remediate. <\/p>\n\n\n\n<p>Retineti ca poti efectua acest proces utilizand si <strong><strong>Media Creation Tool<\/strong>.<\/strong><\/p>\n\n\n\n<p>\u21d2\u00a0<strong><a href=\"https:\/\/windowsreport.com\/software\/download-media-creation-tool\/\" target=\"_blank\" rel=\"noreferrer noopener\">Descarca Media Creation Tool<\/a><\/strong><\/p>\n\n\n\n<p>Apoi selecteaza optiunea <strong><strong>Upgrade this PC now<\/strong><\/strong>. Instrumentul va descarca fisierele necesare si te va indruma spre procesul de actualizare.<\/p>\n\n\n\n<p>Putini utilizatori sustin ca poti rezolva aceasta problema resetand Windows 10, dar aceasta este o solutie drastica care iti va sterge toate fisierele.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>Gata, speram ca cel putin una dintre aceste solutii te-a ajutat sa va rezolvi problema cu aplicatia Mail care nu functioneaza in Windows 10.<\/p>\n\n\n\n<p>Daca ai sugestii, intrebari sau poate vreo alta solutie pentru problema aplicatiei Mail in Windows 10, lasa comentariile tale in sectiunea de mai jos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft si-a imbunatatit mult aplicatia Mail incorporata in Windows 10. Dar chiar si in versiunea imbunatatita, unii oameni raporteaza ca nu pot primi e-mailuri sau chiar ca nu pot deschide aplicatia. Asadar, am pregatit cateva solutii care speram ca vor fi suficiente pentru rezolvarea problemei cu aplicatia Mail care nu functioneaza in Windows 10. Daca [&hellip;]<\/p>\n","protected":false},"author":255,"featured_media":2435,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_enabled_clarity":"","footnotes":""},"categories":[985],"tags":[],"work":[],"class_list":["post-2433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ghid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10<\/title>\n<meta name=\"description\" content=\"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10\" \/>\n<meta property=\"og:description\" content=\"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/\" \/>\n<meta property=\"og:site_name\" content=\"WindowsReport - Viata high-tech fara erori\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WindowsReport\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T08:21:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T11:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claudiu Andone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AndoneClaudiu\" \/>\n<meta name=\"twitter:site\" content=\"@WindowsRep\" \/>\n<meta name=\"twitter:label1\" content=\"Scris de\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claudiu Andone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/\"},\"author\":{\"name\":\"Claudiu Andone\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#\\\/schema\\\/person\\\/d9728f71f0fcd96251f5280057b543ee\"},\"headline\":\"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10\",\"datePublished\":\"2021-03-31T08:21:04+00:00\",\"dateModified\":\"2025-09-16T11:40:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/\"},\"wordCount\":3432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/03\\\/Aplicatia-Mail-nu-functioneaza.jpg\",\"articleSection\":[\"Tutoriale\"],\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#respond\"]}],\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/\",\"name\":\"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/03\\\/Aplicatia-Mail-nu-functioneaza.jpg\",\"datePublished\":\"2021-03-31T08:21:04+00:00\",\"dateModified\":\"2025-09-16T11:40:48+00:00\",\"description\":\"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/03\\\/Aplicatia-Mail-nu-functioneaza.jpg\",\"contentUrl\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/03\\\/Aplicatia-Mail-nu-functioneaza.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Cum se repara aplicatia Mail\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/aplicatia-mail-nu-functioneaza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutoriale\",\"item\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/category\\\/ghid\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aplicatia Mail nu functioneaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/\",\"name\":\"WindowsReport - Viata high-tech fara erori\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#organization\",\"name\":\"WindowsReport - Viata high-tech fara erori\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/wr-logo-default.png\",\"contentUrl\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2024\\\/01\\\/wr-logo-default.png\",\"width\":214,\"height\":35,\"caption\":\"WindowsReport - Viata high-tech fara erori\"},\"image\":{\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WindowsReport\",\"https:\\\/\\\/x.com\\\/WindowsRep\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/#\\\/schema\\\/person\\\/d9728f71f0fcd96251f5280057b543ee\",\"name\":\"Claudiu Andone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/Claudiu-Andone.jpg\",\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/Claudiu-Andone.jpg\",\"contentUrl\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/Claudiu-Andone.jpg\",\"caption\":\"Claudiu Andone\"},\"description\":\"Oldtimer in the tech and science press, Claudiu is focused on whatever comes new from Microsoft. His abrupt interest in computers started when he saw the first Home Computer as a kid. However, his passion for Windows and everything related became obvious when he became a sys admin in a computer science high school. With 14 years of experience in writing about everything there is to know about science and technology, Claudiu also likes rock music, chilling in the garden, and Star Wars. May the force be with you, always!\",\"sameAs\":[\"https:\\\/\\\/windowsreport.com\",\"https:\\\/\\\/www.instagram.com\\\/stormcloud1978\\\/?hl=en\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/claudiu-andone-68b6a96\\\/?originalSubdomain=ro\",\"https:\\\/\\\/x.com\\\/AndoneClaudiu\"],\"url\":\"https:\\\/\\\/windowsreport.com\\\/ro\\\/author\\\/claudiu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10","description":"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/","og_locale":"ro_RO","og_type":"article","og_title":"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10","og_description":"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.","og_url":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/","og_site_name":"WindowsReport - Viata high-tech fara erori","article_publisher":"https:\/\/www.facebook.com\/WindowsReport","article_published_time":"2021-03-31T08:21:04+00:00","article_modified_time":"2025-09-16T11:40:48+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg","type":"image\/jpeg"}],"author":"Claudiu Andone","twitter_card":"summary_large_image","twitter_creator":"@AndoneClaudiu","twitter_site":"@WindowsRep","twitter_misc":{"Scris de":"Claudiu Andone","Timp estimat pentru citire":"17 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#article","isPartOf":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/"},"author":{"name":"Claudiu Andone","@id":"https:\/\/windowsreport.com\/ro\/#\/schema\/person\/d9728f71f0fcd96251f5280057b543ee"},"headline":"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10","datePublished":"2021-03-31T08:21:04+00:00","dateModified":"2025-09-16T11:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/"},"wordCount":3432,"commentCount":0,"publisher":{"@id":"https:\/\/windowsreport.com\/ro\/#organization"},"image":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#primaryimage"},"thumbnailUrl":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg","articleSection":["Tutoriale"],"inLanguage":"ro-RO","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#respond"]}],"copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/windowsreport.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/","url":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/","name":"SOLUTIE: Aplicatia Mail nu functioneaza in Windows 10","isPartOf":{"@id":"https:\/\/windowsreport.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#primaryimage"},"image":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#primaryimage"},"thumbnailUrl":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg","datePublished":"2021-03-31T08:21:04+00:00","dateModified":"2025-09-16T11:40:48+00:00","description":"Multi utilizatori au raportat ca aplicatia Mail nu functioneaza in Windows 10. De aceea iti vom arata cum sa o repari.","breadcrumb":{"@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#primaryimage","url":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg","contentUrl":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2021\/03\/Aplicatia-Mail-nu-functioneaza.jpg","width":1920,"height":1280,"caption":"Cum se repara aplicatia Mail"},{"@type":"BreadcrumbList","@id":"https:\/\/windowsreport.com\/ro\/aplicatia-mail-nu-functioneaza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/windowsreport.com\/ro\/"},{"@type":"ListItem","position":2,"name":"Tutoriale","item":"https:\/\/windowsreport.com\/ro\/category\/ghid\/"},{"@type":"ListItem","position":3,"name":"Aplicatia Mail nu functioneaza"}]},{"@type":"WebSite","@id":"https:\/\/windowsreport.com\/ro\/#website","url":"https:\/\/windowsreport.com\/ro\/","name":"WindowsReport - Viata high-tech fara erori","description":"","publisher":{"@id":"https:\/\/windowsreport.com\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/windowsreport.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/windowsreport.com\/ro\/#organization","name":"WindowsReport - Viata high-tech fara erori","url":"https:\/\/windowsreport.com\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/windowsreport.com\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2024\/01\/wr-logo-default.png","contentUrl":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2024\/01\/wr-logo-default.png","width":214,"height":35,"caption":"WindowsReport - Viata high-tech fara erori"},"image":{"@id":"https:\/\/windowsreport.com\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WindowsReport","https:\/\/x.com\/WindowsRep"]},{"@type":"Person","@id":"https:\/\/windowsreport.com\/ro\/#\/schema\/person\/d9728f71f0fcd96251f5280057b543ee","name":"Claudiu Andone","image":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2020\/10\/Claudiu-Andone.jpg","url":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2020\/10\/Claudiu-Andone.jpg","contentUrl":"https:\/\/windowsreport.com\/ro\/wp-content\/uploads\/sites\/6\/2020\/10\/Claudiu-Andone.jpg","caption":"Claudiu Andone"},"description":"Oldtimer in the tech and science press, Claudiu is focused on whatever comes new from Microsoft. His abrupt interest in computers started when he saw the first Home Computer as a kid. However, his passion for Windows and everything related became obvious when he became a sys admin in a computer science high school. With 14 years of experience in writing about everything there is to know about science and technology, Claudiu also likes rock music, chilling in the garden, and Star Wars. May the force be with you, always!","sameAs":["https:\/\/windowsreport.com","https:\/\/www.instagram.com\/stormcloud1978\/?hl=en","https:\/\/www.linkedin.com\/in\/claudiu-andone-68b6a96\/?originalSubdomain=ro","https:\/\/x.com\/AndoneClaudiu"],"url":"https:\/\/windowsreport.com\/ro\/author\/claudiu\/"}]}},"_links":{"self":[{"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/posts\/2433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/users\/255"}],"replies":[{"embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/comments?post=2433"}],"version-history":[{"count":8,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/posts\/2433\/revisions"}],"predecessor-version":[{"id":2444,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/posts\/2433\/revisions\/2444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/media\/2435"}],"wp:attachment":[{"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/media?parent=2433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/categories?post=2433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/tags?post=2433"},{"taxonomy":"work","embeddable":true,"href":"https:\/\/windowsreport.com\/ro\/wp-json\/wp\/v2\/work?post=2433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}